{"id":141905,"date":"2026-02-11T20:11:49","date_gmt":"2026-02-11T20:11:49","guid":{"rendered":"https:\/\/myvalentina.store\/?post_type=product&#038;p=141905"},"modified":"2026-05-04T21:38:58","modified_gmt":"2026-05-04T21:38:58","slug":"body-stone","status":"publish","type":"product","link":"https:\/\/myvalentina.store\/es\/producto\/body-stone\/","title":{"rendered":"Cuerpo de piedra"},"content":{"rendered":"<p>Body de licra con detalle efecto piedra en el centro del pecho. Lleva el\u00e1stico, tirantes y copas ajustables.<\/p>\n<p>El modelo est\u00e1 disponible en las tallas: S\/M y M\/L<\/p>\n<p>A modo de comparaci\u00f3n, la modelo mide 1,64 m, viste XS\/S y lleva S\/M.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Body de licra con detalle efecto piedra en el centro del pecho. Lleva el\u00e1stico, tirantes y copas ajustables.<\/p>\n<p>El modelo est\u00e1 disponible en las tallas: S\/M y M\/L<\/p>\n<p>A modo de comparaci\u00f3n, la modelo mide 1,64 m, viste XS\/S y lleva S\/M.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":141913,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[170,155],"product_tag":[],"class_list":{"0":"post-141905","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-body-vestuario","7":"product_cat-collection","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"layout-style-1","16":"col-md-4 col-sm-4 col-xs-6","17":"col-lg-4","18":"product-has-gallery","19":"product-style-default"},"_links":{"self":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/141905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/comments?post=141905"}],"version-history":[{"count":1,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/141905\/revisions"}],"predecessor-version":[{"id":141922,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/141905\/revisions\/141922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media\/141913"}],"wp:attachment":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media?parent=141905"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_brand?post=141905"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_cat?post=141905"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_tag?post=141905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}