{"id":146086,"date":"2026-07-15T18:18:45","date_gmt":"2026-07-15T18:18:45","guid":{"rendered":"https:\/\/myvalentina.store\/?post_type=product&#038;p=146086"},"modified":"2026-07-15T19:29:34","modified_gmt":"2026-07-15T19:29:34","slug":"conjunto-ivory-muse","status":"publish","type":"product","link":"https:\/\/myvalentina.store\/es\/producto\/conjunto-ivory-muse\/","title":{"rendered":"Conjunto Ivory Muse"},"content":{"rendered":"<p>Conjunto elegante em tecido tipo fato, composto por top de inspira\u00e7\u00e3o oriental com decote halter e fecho frontal de atilhos. As cal\u00e7as de perna larga t\u00eam el\u00e1stico na parte de tr\u00e1s da cintura e atilho ajust\u00e1vel, proporcionando um ajuste confort\u00e1vel e favorecedor.<\/p>\n<p>El modelo est\u00e1 disponible en las tallas: S\/M y M\/L<\/p>\n<p>Como compara\u00e7\u00e3o, a modelo mede 1.64m, veste XS\/S, est\u00e1 com o S\/M vestido e com uns saltos de 8cm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Conjunto elegante em tecido tipo fato, composto por top de inspira\u00e7\u00e3o oriental com decote halter e fecho frontal de atilhos. As cal\u00e7as de perna larga t\u00eam el\u00e1stico na parte de tr\u00e1s da cintura e atilho ajust\u00e1vel, proporcionando um ajuste confort\u00e1vel e favorecedor.<\/p>\n<p>El modelo est\u00e1 disponible en las tallas: S\/M y M\/L<\/p>\n<p>Como compara\u00e7\u00e3o, a modelo mede 1.64m, veste XS\/S, est\u00e1 com o S\/M vestido e com uns saltos de 8cm.<\/p>","protected":false},"featured_media":146096,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[155,173],"product_tag":[],"class_list":{"0":"post-146086","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-collection","7":"product_cat-conjuntos-vestuario","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"new","16":"layout-style-1","17":"col-md-4 col-sm-4 col-xs-6","18":"col-lg-4","19":"product-has-gallery","20":"product-style-default"},"_links":{"self":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/comments?post=146086"}],"version-history":[{"count":1,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146086\/revisions"}],"predecessor-version":[{"id":146118,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146086\/revisions\/146118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media\/146096"}],"wp:attachment":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media?parent=146086"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_brand?post=146086"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_cat?post=146086"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_tag?post=146086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}