{"id":146415,"date":"2026-08-11T17:23:40","date_gmt":"2026-08-11T17:23:40","guid":{"rendered":"https:\/\/myvalentina.store\/?post_type=product&#038;p=146415"},"modified":"2026-08-27T20:17:19","modified_gmt":"2026-08-27T20:17:19","slug":"conjunto-mia","status":"publish","type":"product","link":"https:\/\/myvalentina.store\/es\/producto\/conjunto-mia\/","title":{"rendered":"Macac\u00e3o Mia"},"content":{"rendered":"<p>Macac\u00e3o de corte fluido e elegante, com decote halter e detalhe drapeado na parte frontal. Possui copas incorporadas, costas com el\u00e1stico para um ajuste confort\u00e1vel e aperta atrav\u00e9s de atilhos no pesco\u00e7o. Perfeito tanto para um look descontra\u00eddo de ver\u00e3o como para uma ocasi\u00e3o especial.<\/p>\n<p>El modelo es talla \u00fanica y sirve para: S M L<\/p>\n<p>Como compara\u00e7\u00e3o, a modelo mede 1.64m, veste XS\/S e com uns saltos de 8cm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Macac\u00e3o de corte fluido e elegante, com decote halter e detalhe drapeado na parte frontal. Possui copas incorporadas, costas com el\u00e1stico para um ajuste confort\u00e1vel e aperta atrav\u00e9s de atilhos no pesco\u00e7o. Perfeito tanto para um look descontra\u00eddo de ver\u00e3o como para uma ocasi\u00e3o especial.<\/p>\n<p>El modelo es talla \u00fanica y sirve para: S M L<\/p>\n<p>Como compara\u00e7\u00e3o, a modelo mede 1.64m, veste XS\/S e com uns saltos de 8cm.<\/p>","protected":false},"featured_media":146528,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[155,16023],"product_tag":[],"class_list":{"0":"post-146415","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-collection","7":"product_cat-macacao","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"layout-style-1","16":"col-md-4 col-sm-4 col-xs-6","17":"col-lg-4","18":"product-has-gallery","19":"product-style-default"},"_links":{"self":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/comments?post=146415"}],"version-history":[{"count":5,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146415\/revisions"}],"predecessor-version":[{"id":146481,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product\/146415\/revisions\/146481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media\/146528"}],"wp:attachment":[{"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/media?parent=146415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_brand?post=146415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_cat?post=146415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myvalentina.store\/es\/wp-json\/wp\/v2\/product_tag?post=146415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}